{"id":7564,"date":"2020-03-06T11:50:40","date_gmt":"2020-03-06T10:50:40","guid":{"rendered":"https:\/\/elviolinexperiencia.com\/contact\/"},"modified":"2023-11-14T10:45:21","modified_gmt":"2023-11-14T09:45:21","slug":"contact","status":"publish","type":"page","link":"https:\/\/elviolinexperiencia.com\/nl\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;portada-pagina portada&#8221; _builder_version=&#8221;4.22.1&#8243; background_enable_color=&#8221;off&#8221; background_image=&#8221;https:\/\/elviolinexperiencia.com\/wp-content\/uploads\/2023\/08\/portadahotel.jpg&#8221; background_position=&#8221;bottom_center&#8221; custom_padding=&#8221;100px||450px||false|false&#8221; bottom_divider_color=&#8221;#FFFFFF&#8221; bottom_divider_flip=&#8221;vertical&#8221; bottom_divider_arrangement=&#8221;above_content&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;T\u00edtulo&#8221; _builder_version=&#8221;4.22.1&#8243; text_text_color=&#8221;#ffffff&#8221; text_font_size=&#8221;18px&#8221; header_font=&#8221;|700|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;55px&#8221; header_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; header_text_shadow_style=&#8221;preset1&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h1>Contact<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Kaisei Opti|700|||||||&#8221; text_font_size=&#8221;36px&#8221; text_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; background_layout=&#8221;dark&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; text_text_shadow_style=&#8221;preset1&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Nog vragen? Wij helpen u graag.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Breadcrumbs&#8221; module_id=&#8221;breadcrumbs&#8221; _builder_version=&#8221;4.22.1&#8243; background_color=&#8221;#cccccc&#8221; background_enable_color=&#8221;off&#8221; custom_padding=&#8221;30px||0px||false|false&#8221; global_module=&#8221;3246&#8243; locked=&#8221;off&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.22.1&#8243; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_code _builder_version=&#8221;4.22.1&#8243; text_orientation=&#8221;center&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<nav aria-label=\"breadcrumbs\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Inicio<\/span><\/p><\/nav>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;seccion seccion-contacto contacta-con-nosotros&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;FORMULARIO DE CONTACTO&#8221; _builder_version=&#8221;4.22.1&#8243; header_2_font=&#8221;Kaisei Opti|700|||||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>CONTACT FORMULIER<\/h2>\n<p>[\/et_pb_text][et_pb_code admin_label=&#8221;Contactformuliervelden&#8221; module_class=&#8221;formulario-contacto&#8221; _builder_version=&#8221;4.22.1&#8243; global_colors_info=&#8221;{}&#8221;]\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f7663-o1\" lang=\"nl-NL\" dir=\"ltr\" data-wpcf7-id=\"7663\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/nl\/wp-json\/wp\/v2\/pages\/7564#wpcf7-f7663-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contactformulier\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"7663\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"nl_NL\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f7663-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"cf7-custom-css\">\n    <div class=\"fields\">\n        <div class=\"field-item\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Naam\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/div>\n    <\/div>\n    <div class=\"fields fields-cols\">\n        <div class=\"field-item\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/div>\n        <div class=\"field-item field-item-last\"><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-104\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Mobiel Nummer\" value=\"\" type=\"tel\" name=\"tel-104\" \/><\/span><\/div>\n    <\/div>\n    <div class=\"fields\">\n        <div class=\"field-item\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Hoe kan ik u helpen?\" name=\"your-message\"><\/textarea><\/span><\/div>\n    <\/div>\n    <div class=\"conditions\">\n        <p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-254\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-254\" value=\"1\" id=\"validarPolitica\" aria-invalid=\"false\" \/><\/span><\/span><\/span> Ik heb het privacybeleid <a href=\"https:\/\/elviolinexperiencia.com\/politica-privacidad\/\" rel=\"nofollow\" target=\"_blank\">gelezen en accepteer<\/a> het.<\/p>\n    <\/div>\n    <div class=\"submit\"><input class=\"wpcf7-form-control wpcf7-submit has-spinner et_pb_contact_submit et_pb_button\" type=\"submit\" value=\"Enviar\" \/><\/div>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"246\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n[\/et_pb_code][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;INFORMACI\u00d3N DE CONTACTO&#8221; _builder_version=&#8221;4.22.1&#8243; header_2_font=&#8221;Kaisei Opti|700|||||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>CONTACTGEGEVENS<\/h2>\n<p>[\/et_pb_text][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe090;||divi||400&#8243; icon_color=&#8221;#303030&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;26px&#8221; admin_label=&#8221;Tel\u00e9fono&#8221; _builder_version=&#8221;4.22.1&#8243; body_font=&#8221;|700|||||||&#8221; body_text_color=&#8221;#303030&#8243; body_font_size=&#8221;20px&#8221; icon_font_size=&#8221;26px&#8221; global_colors_info=&#8221;{}&#8221;]<strong>744 478 839<\/strong>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf232;||fa||400&#8243; icon_color=&#8221;#303030&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;26px&#8221; admin_label=&#8221;Whatsapp&#8221; _builder_version=&#8221;4.22.1&#8243; body_font=&#8221;|700|||||||&#8221; body_text_color=&#8221;#303030&#8243; body_font_size=&#8221;20px&#8221; link_option_url=&#8221;https:\/\/wa.me\/34744478839&#8243; icon_font_size=&#8221;26px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Stuur whatsapp<\/strong><\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x7d;||divi||400&#8243; icon_color=&#8221;#303030&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;26px&#8221; admin_label=&#8221;Horario&#8221; _builder_version=&#8221;4.22.1&#8243; body_text_color=&#8221;#303030&#8243; icon_font_size=&#8221;26px&#8221; global_colors_info=&#8221;{}&#8221;]9:30 \u2013 14:00 hrs<br \/>\n16:00-20:00 hrs[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe081;||divi||400&#8243; icon_color=&#8221;#303030&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;26px&#8221; admin_label=&#8221;Direcci\u00f3n&#8221; _builder_version=&#8221;4.22.1&#8243; body_text_color=&#8221;#303030&#8243; icon_font_size=&#8221;26px&#8221; global_colors_info=&#8221;{}&#8221;]Avenida del valle 2A, 18658<br \/>\nMelegis\/ El Valle (GRANADA)[\/et_pb_blurb][et_pb_social_media_follow _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/people\/El-Violin-Experiencia\/100063821842853\/&#8221; icon_color=&#8221;#2B3062&#8243; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#D9D9D9&#8243; background_enable_color=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; url=&#8221;https:\/\/www.instagram.com\/elviolin_experiencia\/&#8221; icon_color=&#8221;#2B3062&#8243; _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#D9D9D9&#8243; background_enable_color=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; module_class=&#8221;seccion seccion-contacto contenedor-mapa&#8221; _builder_version=&#8221;4.22.1&#8243; max_height=&#8221;450px&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row use_custom_gutter=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;INFORMACI\u00d3N DE CONTACTO&#8221; _builder_version=&#8221;4.22.1&#8243; header_2_font=&#8221;Kaisei Opti|700|||||||&#8221; header_2_text_align=&#8221;center&#8221; custom_margin=&#8221;||10px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>WAAR WE ZIJN?<\/h2>\n<p>[\/et_pb_text][et_pb_code _builder_version=&#8221;4.22.1&#8243; global_colors_info=&#8221;{}&#8221;]<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3189.0351378963796!2d-3.5697858241553693!3d36.93732757220829!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0xd71ed527e8323d9%3A0xc2685fd6a7c4e823!2sEl%20Violin%20Experiencia!5e0!3m2!1ses!2ses!4v1693558247590!5m2!1ses!2ses\" width=\"100%\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ContactNog vragen? Wij helpen u graag.<nav aria-label=\"breadcrumbs\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Inicio<\/span><\/p><\/nav>CONTACT FORMULIER\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f7663-o2\" lang=\"nl-NL\" dir=\"ltr\" data-wpcf7-id=\"7663\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/nl\/wp-json\/wp\/v2\/pages\/7564#wpcf7-f7663-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contactformulier\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"7663\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"nl_NL\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f7663-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"cf7-custom-css\">\n    <div class=\"fields\">\n        <div class=\"field-item\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Naam\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span><\/div>\n    <\/div>\n    <div class=\"fields fields-cols\">\n        <div class=\"field-item\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span><\/div>\n        <div class=\"field-item field-item-last\"><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-104\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Mobiel Nummer\" value=\"\" type=\"tel\" name=\"tel-104\" \/><\/span><\/div>\n    <\/div>\n    <div class=\"fields\">\n        <div class=\"field-item\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Hoe kan ik u helpen?\" name=\"your-message\"><\/textarea><\/span><\/div>\n    <\/div>\n    <div class=\"conditions\">\n        <p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-254\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acceptance-254\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span> Ik heb het privacybeleid <a href=\"https:\/\/elviolinexperiencia.com\/politica-privacidad\/\" rel=\"nofollow\" target=\"_blank\">gelezen en accepteer<\/a> het.<\/p>\n    <\/div>\n    <div class=\"submit\"><input class=\"wpcf7-form-control wpcf7-submit has-spinner et_pb_contact_submit et_pb_button\" type=\"submit\" value=\"Enviar\" \/><\/div>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_2\" name=\"_wpcf7_ak_js\" value=\"249\"\/><script>\ndocument.getElementById( \"ak_js_2\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\nCONTACTGEGEVENS744 478 839Stuur whatsapp9:30 \u2013 14:00 hrs 16:00-20:00 hrsAvenida del valle 2A, 18658 Melegis\/ El Valle (GRANADA)WAAR WE ZIJN?<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-7564","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/elviolinexperiencia.com\/nl\/wp-json\/wp\/v2\/pages\/7564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elviolinexperiencia.com\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elviolinexperiencia.com\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elviolinexperiencia.com\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elviolinexperiencia.com\/nl\/wp-json\/wp\/v2\/comments?post=7564"}],"version-history":[{"count":0,"href":"https:\/\/elviolinexperiencia.com\/nl\/wp-json\/wp\/v2\/pages\/7564\/revisions"}],"wp:attachment":[{"href":"https:\/\/elviolinexperiencia.com\/nl\/wp-json\/wp\/v2\/media?parent=7564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}